{"id":17340,"date":"2022-09-05T09:45:35","date_gmt":"2022-09-05T07:45:35","guid":{"rendered":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067.jpg"},"modified":"2022-09-05T09:45:35","modified_gmt":"2022-09-05T07:45:35","slug":"img_3067","status":"inherit","type":"attachment","link":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/img_3067","title":{"rendered":"IMG_3067"},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout"},"class_list":["post-17340","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"17340\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/img_3067\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX210 IS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1662214853&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;57.619&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_3067\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?fit=800%2C600&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":600,"file":"2022\/09\/IMG_3067-scaled-e1662365211912.jpg","filesize":723365,"sizes":{"medium":{"file":"IMG_3067-scaled-e1662365211912-300x225.jpg","width":300,"height":225,"filesize":19419,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?fit=300%2C225&ssl=1"},"large":{"file":"IMG_3067-1024x768.jpg","width":1024,"height":768,"filesize":161243,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?fit=800%2C600&ssl=1"},"thumbnail":{"file":"IMG_3067-scaled-e1662365211912-150x150.jpg","width":150,"height":150,"filesize":7995,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"IMG_3067-scaled-e1662365211912-768x576.jpg","width":768,"height":576,"filesize":89850,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?fit=768%2C576&ssl=1"},"1536x1536":{"file":"IMG_3067-1536x1152.jpg","width":1536,"height":1152,"filesize":311595,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?fit=1536%2C1152&ssl=1"},"2048x2048":{"file":"IMG_3067-2048x1536.jpg","width":2048,"height":1536,"filesize":497932,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?fit=2048%2C1536&ssl=1"},"colormag-highlighted-post":{"file":"IMG_3067-scaled-e1662365211912-392x272.jpg","width":392,"height":272,"filesize":27823,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?resize=392%2C272&ssl=1"},"colormag-featured-post-medium":{"file":"IMG_3067-scaled-e1662365211912-390x205.jpg","width":390,"height":205,"filesize":22462,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?resize=390%2C205&ssl=1"},"colormag-featured-post-small":{"file":"IMG_3067-scaled-e1662365211912-130x90.jpg","width":130,"height":90,"filesize":4720,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?resize=130%2C90&ssl=1"},"colormag-featured-image":{"file":"IMG_3067-scaled-e1662365211912-800x445.jpg","width":800,"height":445,"filesize":80507,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?resize=800%2C445&ssl=1"},"mailpoet_newsletter_max":{"file":"IMG_3067-1320x990.jpg","width":1320,"height":990,"filesize":244506,"mime_type":"image\/jpeg","source_url":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-1320x990.jpg"},"full":{"file":"IMG_3067-scaled-e1662365211912.jpg?fit=800%2C600&ssl=1","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg?fit=800%2C600&ssl=1"}},"image_meta":{"aperture":"5.6","credit":"","camera":"Canon PowerShot SX210 IS","caption":"","created_timestamp":"1662214853","copyright":"","focal_length":"57.619","iso":"400","shutter_speed":"0.002","title":"","orientation":"1","keywords":[]},"original_image":"IMG_3067.jpg"},"post":null,"source_url":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3067-scaled-e1662365211912.jpg","_links":{"self":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media\/17340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=17340"}]}}