{"id":17350,"date":"2022-09-05T09:46:55","date_gmt":"2022-09-05T07:46:55","guid":{"rendered":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093.jpg"},"modified":"2022-09-05T09:46:55","modified_gmt":"2022-09-05T07:46:55","slug":"img_3093","status":"inherit","type":"attachment","link":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/img_3093","title":{"rendered":"IMG_3093"},"author":49,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout"},"class_list":["post-17350","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?resize=768%2C575&amp;ssl=1 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"17350\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/img_3093\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?fit=800%2C599&amp;ssl=1\" data-orig-size=\"800,599\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX210 IS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1662216915&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;28.289&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_3093\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?fit=800%2C599&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":599,"file":"2022\/09\/IMG_3093-e1662364949143.jpg","filesize":492262,"sizes":{"medium":{"file":"IMG_3093-e1662364949143-300x225.jpg","width":300,"height":225,"filesize":20743,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?fit=300%2C225&ssl=1"},"large":{"file":"IMG_3093-1024x767.jpg","width":1024,"height":767,"filesize":146154,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?fit=800%2C599&ssl=1"},"thumbnail":{"file":"IMG_3093-e1662364949143-150x150.jpg","width":150,"height":150,"filesize":8211,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"IMG_3093-e1662364949143-768x575.jpg","width":768,"height":575,"filesize":85294,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?fit=768%2C575&ssl=1"},"colormag-highlighted-post":{"file":"IMG_3093-e1662364949143-392x272.jpg","width":392,"height":272,"filesize":28815,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?resize=392%2C272&ssl=1"},"colormag-featured-post-medium":{"file":"IMG_3093-e1662364949143-390x205.jpg","width":390,"height":205,"filesize":22839,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?resize=390%2C205&ssl=1"},"colormag-featured-post-small":{"file":"IMG_3093-e1662364949143-130x90.jpg","width":130,"height":90,"filesize":5452,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?resize=130%2C90&ssl=1"},"colormag-featured-image":{"file":"IMG_3093-e1662364949143-800x445.jpg","width":800,"height":445,"filesize":74858,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?resize=800%2C445&ssl=1"},"full":{"file":"IMG_3093-e1662364949143.jpg?fit=800%2C599&ssl=1","width":800,"height":599,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg?fit=800%2C599&ssl=1"}},"image_meta":{"aperture":"5","credit":"","camera":"Canon PowerShot SX210 IS","caption":"","created_timestamp":"1662216915","copyright":"","focal_length":"28.289","iso":"200","shutter_speed":"0.005","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2022\/09\/IMG_3093-e1662364949143.jpg","_links":{"self":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media\/17350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=17350"}]}}