{"id":7596,"date":"2015-05-03T22:27:40","date_gmt":"2015-05-03T21:27:40","guid":{"rendered":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02.jpg"},"modified":"2015-05-03T22:28:33","modified_gmt":"2015-05-03T21:28:33","slug":"02","status":"inherit","type":"attachment","link":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/02","title":{"rendered":"02"},"author":39,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout"},"class_list":["post-7596","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"253\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02.jpg?fit=190%2C253&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Serkan\" data-attachment-id=\"7596\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/02\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02.jpg?fit=190%2C253&amp;ssl=1\" data-orig-size=\"190,253\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D90&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1430663725&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;105&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.003125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"02\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Serkan l\u00e4sst sich nicht absch\u00fctteln&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02.jpg?fit=190%2C253&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Serkan l\u00e4sst sich nicht absch\u00fctteln<\/p>\n"},"alt_text":"Serkan","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":190,"height":253,"file":"2015\/05\/02.jpg","sizes":{"woocommerce_gallery_thumbnail":{"file":"02-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02-100x100.jpg"},"thumbnail":{"file":"02-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02.jpg?resize=150%2C150&ssl=1"},"post-thumbnail":{"file":"02-190x198.jpg","width":190,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02-190x198.jpg"},"full":{"file":"02.jpg?fit=190%2C253&ssl=1","width":190,"height":253,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02.jpg?fit=190%2C253&ssl=1"}},"image_meta":{"aperture":"8","credit":"","camera":"NIKON D90","caption":"","created_timestamp":"1430663725","copyright":"","focal_length":"105","iso":"800","shutter_speed":"0.003125","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2015\/05\/02.jpg","_links":{"self":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media\/7596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=7596"}]}}