{"id":19966,"date":"2023-08-29T21:53:55","date_gmt":"2023-08-29T19:53:55","guid":{"rendered":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/?p=19966"},"modified":"2023-08-29T21:53:55","modified_gmt":"2023-08-29T19:53:55","slug":"erste-unterliegt-hagen-hardissen-de-maggio-einstand-32-gegen-horn","status":"publish","type":"post","link":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/19966","title":{"rendered":"Erste unterliegt Hagen Hardissen &#8211; De Maggio Einstand 3:2 gegen Horn"},"content":{"rendered":"<p>Unsere Erste Herrenmannschaft war gegen die SpVg Hagen Hardissen am 3. Spieltag machtlos. Die deutliche \u00dcberlegenheit der G\u00e4ste spiegelte sich im klaren Endergebnis 1:8 wider.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19968\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/19966\/tp5i1a2743\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2743.jpg?fit=1200%2C675&amp;ssl=1\" data-orig-size=\"1200,675\" data-comments-opened=\"0\" data-image-title=\"tp5I1A2743\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2743.jpg?fit=800%2C450&amp;ssl=1\" class=\"alignnone size-full wp-image-19968\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2743.jpg?resize=800%2C450&#038;ssl=1\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2743.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2743.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2743.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2743.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"19969\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/19966\/tp5i1a2751\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2751.jpg?fit=1200%2C675&amp;ssl=1\" data-orig-size=\"1200,675\" data-comments-opened=\"0\" data-image-title=\"tp5I1A2751\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2751.jpg?fit=800%2C450&amp;ssl=1\" class=\"alignnone size-full wp-image-19969\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2751.jpg?resize=800%2C450&#038;ssl=1\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2751.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2751.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2751.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2751.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Das 17Uhr Spiel am Sonntag war der Ligaauftakt f\u00fcr unsere Zweite. Coach Leonardo De Maggio feierte mit seinem Team einen gelungenen Einstand. Nach einem 0:2 Pausenr\u00fcckstand drehte Gr\u00fcn\/Wei\u00df im zweiten Durchgang die Partie. Sherif Emini (50. Min), Marco De Jager Schwane (65te) und Ahmed Yusuf in der 85ten Minute lie\u00dfen mit ihren Treffern die Gr\u00fcn\/Wei\u00dfen jubeln. Nach 90 packenden Minuten war am Ende die Zweitvertretung des TuS Horn-Bad Meinberg mit 3:2 besiegt. (Bilder im Bericht aus der Partie TuS I gegen Hagen Hardissen)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erste unterliegt Hagen Hardissen &#8211; De Maggio Einstand 3:2 gegen Horn <\/p>\n","protected":false},"author":16,"featured_media":19967,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[157,159],"tags":[],"class_list":["post-19966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv","category-fb-senioren-aktuell"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2023\/08\/tp5I1A2727.jpg?fit=1200%2C675&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/posts\/19966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=19966"}],"version-history":[{"count":0,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/posts\/19966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media\/19967"}],"wp:attachment":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=19966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=19966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=19966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}