{"id":23880,"date":"2026-05-12T16:48:26","date_gmt":"2026-05-12T14:48:26","guid":{"rendered":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/?p=23880"},"modified":"2026-05-12T16:48:26","modified_gmt":"2026-05-12T14:48:26","slug":"03-tagesform-entscheidet-top-duell-sc-peckeloh-auf-titelkurs","status":"publish","type":"post","link":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/23880","title":{"rendered":"0:3 &#8211; Tagesform entscheidet Top-Duell &#8211; SC Peckeloh auf Titelkurs"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"23882\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/23880\/tp_55a5620-2\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5620.jpeg?fit=1200%2C675&amp;ssl=1\" data-orig-size=\"1200,675\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;ROLF GEHRKE&quot;,&quot;camera&quot;:&quot;Canon EOS R6m2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778408282&quot;,&quot;copyright&quot;:&quot;zfts301023&quot;,&quot;focal_length&quot;:&quot;100&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"tp_55A5620\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5620.jpeg?fit=800%2C450&amp;ssl=1\" class=\"alignnone size-full wp-image-23882\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5620.jpeg?resize=800%2C450&#038;ssl=1\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5620.jpeg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5620.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5620.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5620.jpeg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>In unsere zweite Saisonniederlage mussten wir am vergangenen Sonntag einwilligen und dem SC Peckeloh, vielleicht auch schon zum Titelgewinn gratulieren. Das 0:3 entspricht allerdings nicht ganz dem Spielverlauf. Insgesamt sahen die begeisterten Zuschauer eine faire und packende Partie auf Augenh\u00f6he, mit herrlichen Spielz\u00fcgen und Torchancen auf beiden Seiten. Wir starteten sogar besser in die Begegnung, waren auch \u00fcber weite Strecken des Spielverlaufs, insbesondere der ersten Halbzeit die spielbestimmende Mannschaft. Im Abschluss fehlte uns leider die erforderliche Pr\u00e4zision und auch oftmals das Qu\u00e4ntchen Fortune.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"23886\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/23880\/tp_55a5666\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5666.jpeg?fit=1200%2C674&amp;ssl=1\" data-orig-size=\"1200,674\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;ROLF GEHRKE&quot;,&quot;camera&quot;:&quot;Canon EOS R6m2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778409753&quot;,&quot;copyright&quot;:&quot;zfts301023&quot;,&quot;focal_length&quot;:&quot;200&quot;,&quot;iso&quot;:&quot;400&quot;,&quot;shutter_speed&quot;:&quot;0.0004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"tp_55A5666\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5666.jpeg?fit=800%2C449&amp;ssl=1\" class=\"alignnone size-full wp-image-23886\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5666.jpeg?resize=800%2C449&#038;ssl=1\" alt=\"\" width=\"800\" height=\"449\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5666.jpeg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5666.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5666.jpeg?resize=1024%2C575&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5666.jpeg?resize=768%2C431&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"23887\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/23880\/tp_55a5668-2\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5668.jpeg?fit=1200%2C674&amp;ssl=1\" data-orig-size=\"1200,674\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;ROLF GEHRKE&quot;,&quot;camera&quot;:&quot;Canon EOS R6m2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778409772&quot;,&quot;copyright&quot;:&quot;zfts301023&quot;,&quot;focal_length&quot;:&quot;88&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.0004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"tp_55A5668\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5668.jpeg?fit=800%2C449&amp;ssl=1\" class=\"alignnone size-full wp-image-23887\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5668.jpeg?resize=800%2C449&#038;ssl=1\" alt=\"\" width=\"800\" height=\"449\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5668.jpeg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5668.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5668.jpeg?resize=1024%2C575&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5668.jpeg?resize=768%2C431&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/> Zwei Gegentreffer schon vor der Pause spielten dem Tabellenf\u00fchrer in die Karten. Mit einer durchweg soliden Defensivleistung verteidigte die gut gestaffelte Abwehrreihe des SC Peckeloh danach nahezu alles weg. Da wir auch mit unsere besten Torchancen an diesem Tage keinen Erfolg hatten, brachte das 0:3 nach einer Stunde Spielzeit die Entscheidung zugunsten des SC Peckeloh.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"23884\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/23880\/tp_55a5689\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5689.jpeg?fit=1200%2C675&amp;ssl=1\" data-orig-size=\"1200,675\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;ROLF GEHRKE&quot;,&quot;camera&quot;:&quot;Canon EOS R6m2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778414083&quot;,&quot;copyright&quot;:&quot;zfts301023&quot;,&quot;focal_length&quot;:&quot;70&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.0004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"tp_55A5689\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5689.jpeg?fit=800%2C450&amp;ssl=1\" class=\"alignnone size-full wp-image-23884\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5689.jpeg?resize=800%2C450&#038;ssl=1\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5689.jpeg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5689.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5689.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5689.jpeg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"23885\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/23880\/tp_55a5690\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5690.jpeg?fit=1200%2C675&amp;ssl=1\" data-orig-size=\"1200,675\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;ROLF GEHRKE&quot;,&quot;camera&quot;:&quot;Canon EOS R6m2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778414083&quot;,&quot;copyright&quot;:&quot;zfts301023&quot;,&quot;focal_length&quot;:&quot;70&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.0004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"tp_55A5690\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5690.jpeg?fit=800%2C450&amp;ssl=1\" class=\"alignnone size-full wp-image-23885\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5690.jpeg?resize=800%2C450&#038;ssl=1\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5690.jpeg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5690.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5690.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5690.jpeg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/> Nach dem Schlusspfiff gratulierten wir den Gegnerinnen zum verdienten Sieg und w\u00fcnschten dem SC Peckeloh viel Erfolg auf dem Wege zum Titelgewinn. Dieser k\u00f6nnte am kommenden Wochenende im n\u00e4chsten Top-Duell gegen TuRa L\u00f6hne verwirklicht werden. In gem\u00fctlicher Atmosph\u00e4re lie\u00dfen wir anschlie\u00dfend gemeinsam mit den Gegnerinnen und den begeisterten Fans einen klasse Frauen-Fu\u00dfball-Sonntag ausklingen\u2026<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"23883\" data-permalink=\"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/archives\/23880\/tp_55a5619\" data-orig-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5619.jpeg?fit=1200%2C675&amp;ssl=1\" data-orig-size=\"1200,675\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;ROLF GEHRKE&quot;,&quot;camera&quot;:&quot;Canon EOS R6m2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1778408264&quot;,&quot;copyright&quot;:&quot;zfts301023&quot;,&quot;focal_length&quot;:&quot;102&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.0005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"tp_55A5619\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5619.jpeg?fit=800%2C450&amp;ssl=1\" class=\"alignnone size-full wp-image-23883\" src=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5619.jpeg?resize=800%2C450&#038;ssl=1\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5619.jpeg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5619.jpeg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5619.jpeg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5619.jpeg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/> \u00a0Unser n\u00e4chstes Spiel findet am kommenden Sonntag um 15 Uhr beim SC Vlotho statt, wir freuen uns auf Eure Unterst\u00fctzung<\/p>\n","protected":false},"excerpt":{"rendered":"<p>0:3 &#8211; Tagesform entscheidet Top-Duell &#8211; SC Peckeloh auf Titelkurs <\/p>\n","protected":false},"author":16,"featured_media":23881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[157,252,254],"tags":[],"class_list":["post-23880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv","category-damenmannschaft","category-fb-weiblich-aktuell"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.tuseichholzremmighausen.de\/wordpress\/wp-content\/uploads\/2026\/05\/tp_55A5657.jpeg?fit=1200%2C674&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/posts\/23880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=23880"}],"version-history":[{"count":0,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/posts\/23880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media\/23881"}],"wp:attachment":[{"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=23880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=23880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tuseichholzremmighausen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=23880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}